{"id":837,"date":"2025-04-07T14:08:18","date_gmt":"2025-04-07T17:08:18","guid":{"rendered":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/?page_id=837"},"modified":"2025-04-07T14:46:16","modified_gmt":"2025-04-07T17:46:16","slug":"sobre-nos","status":"publish","type":"page","link":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/sobre-nos\/","title":{"rendered":"Sobre N\u00f3s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"837\" class=\"elementor elementor-837\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7335cea e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"7335cea\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5512ff4 elementor-widget elementor-widget-spacer\" data-id=\"5512ff4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7ef692 elementor-widget elementor-widget-heading\" data-id=\"b7ef692\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sobre N\u00f3s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2e7f79 elementor-widget elementor-widget-spacer\" data-id=\"c2e7f79\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfc8c63 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"bfc8c63\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b9ef433 e-con-full e-flex lakit-col-width-auto-no e-container e-con e-child\" data-id=\"b9ef433\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f92da3f elementor-widget elementor-widget-text-editor\" data-id=\"f92da3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Institucional<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d0e259 elementor-widget elementor-widget-heading\" data-id=\"8d0e259\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2J Engenharia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84882de elementor-widget elementor-widget-spacer\" data-id=\"84882de\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da385ba elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"da385ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Do planejamento \u00e0 entrega da obra, oferecemos um acompanhamento completo, com infraestrutura moderna e uma equipe qualificada para enfrentar os desafios mais inovadores da engenharia civil. Utilizamos tecnologia avan\u00e7ada e processos eficientes para garantir os melhores resultados.<\/p><p>Adotamos o conceito one-stop-shop, reunindo todas as solu\u00e7\u00f5es de engenharia em um s\u00f3 lugar, proporcionando mais praticidade e efici\u00eancia para nossos clientes.<\/p><p>Nossa proposta \u00e9 fornecer servi\u00e7os de engenharia e constru\u00e7\u00e3o que realmente alcancem resultados superiores mostrando que \u00e9 poss\u00edvel construir com qualidade e pontualidade.<\/p><p>Os empreendimentos constru\u00eddos pela 2J Engenharia mostram o quanto qualidade \u00e9 importante para n\u00f3s. Entregar uma obra realmente bem-feita \u00e9 o nosso objetivo. Para isso, contamos com uma equipe t\u00e9cnica que tem a miss\u00e3o de encantar nossos clientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-254a5ef e-con-full e-flex lakit-col-width-auto-no e-container e-con e-child\" data-id=\"254a5ef\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c146895 elementor-widget elementor-widget-image\" data-id=\"c146895\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"594\" height=\"735\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/2jexperience-1-1.jpg\" class=\"attachment-large size-large wp-image-843\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/2jexperience-1-1.jpg 594w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/2jexperience-1-1-242x300.jpg 242w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1bf4ed elementor-hidden-desktop e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"f1bf4ed\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c77538 e-con-full e-flex lakit-col-width-auto-no e-container e-con e-child\" data-id=\"1c77538\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9544e elementor-widget elementor-widget-text-editor\" data-id=\"5b9544e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Institucional<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef8a2e4 elementor-widget elementor-widget-heading\" data-id=\"ef8a2e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2J Engenharia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89f2eb4 elementor-widget elementor-widget-spacer\" data-id=\"89f2eb4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0561fdc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0561fdc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Do planejamento \u00e0 entrega da obra, oferecemos um acompanhamento completo, com infraestrutura moderna e uma equipe qualificada para enfrentar os desafios mais inovadores da engenharia civil. Utilizamos tecnologia avan\u00e7ada e processos eficientes para garantir os melhores resultados.<\/p><p>Adotamos o conceito one-stop-shop, reunindo todas as solu\u00e7\u00f5es de engenharia em um s\u00f3 lugar, proporcionando mais praticidade e efici\u00eancia para nossos clientes.<\/p><p>Nossa proposta \u00e9 fornecer servi\u00e7os de engenharia e constru\u00e7\u00e3o que realmente alcancem resultados superiores mostrando que \u00e9 poss\u00edvel construir com qualidade e pontualidade.<\/p><p>Os empreendimentos constru\u00eddos pela 2J Engenharia mostram o quanto qualidade \u00e9 importante para n\u00f3s. Entregar uma obra realmente bem-feita \u00e9 o nosso objetivo. Para isso, contamos com uma equipe t\u00e9cnica que tem a miss\u00e3o de encantar nossos clientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-452d685 elementor-hidden-desktop e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"452d685\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59ead1b elementor-widget elementor-widget-image\" data-id=\"59ead1b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"594\" height=\"735\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/2jexperience-1-1.jpg\" class=\"attachment-large size-large wp-image-843\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/2jexperience-1-1.jpg 594w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/2jexperience-1-1-242x300.jpg 242w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6543ab e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"f6543ab\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-515d5da elementor-widget__width-inherit elementor-widget elementor-widget-spacer\" data-id=\"515d5da\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf6576b elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"bf6576b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mudando vidas e transformando gera\u00e7\u00f5es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-258637b elementor-widget__width-inherit elementor-widget elementor-widget-spacer\" data-id=\"258637b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90f87d3 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-counter\" data-id=\"90f87d3\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">de experi\u00eancia no mercado<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"20\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> anos<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d9169d elementor-widget-mobile__width-inherit elementor-widget elementor-widget-counter\" data-id=\"7d9169d\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\"> desenvolvidos e gerenciados<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1000\" data-from-value=\"995\" data-delimiter=\".\">995<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> projetos<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fa894a e-con-full e-flex lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"1fa894a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bc511e2 e-con-full e-flex lakit-col-width-auto-no e-container e-con e-child\" data-id=\"bc511e2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b10b6 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c5b10b6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Miss\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66ec643 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"66ec643\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desenvolver empreendimentos imobili\u00e1rios \u00fanicos, guiados pela inova\u00e7\u00e3o centrada no cliente e por uma arquitetura de vanguarda, criando valor para todos os p\u00fablicos envolvidos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a0da39 e-con-full e-flex lakit-col-width-auto-no e-container e-con e-child\" data-id=\"6a0da39\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ceec2d elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5ceec2d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vis\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3559e1 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e3559e1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser reconhecida como a empresa que mais entende e melhor atende \u00e0s necessidades de quem quer viver em Bragan\u00e7a Paulista e regi\u00e3o, com excel\u00eancia e diferencia\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4ab61a e-con-full e-flex lakit-col-width-auto-no e-container e-con e-child\" data-id=\"e4ab61a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e4d73c elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2e4d73c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Valores<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-938782d elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"938782d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conduzir as a\u00e7\u00f5es com \u00e9tica, respeito e responsabilidade, tanto com clientes e colaboradores quanto com a sociedade e o meio ambiente, mantendo sempre a transpar\u00eancia e promovendo rela\u00e7\u00f5es justas e equilibradas em todas as intera\u00e7\u00f5es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d412346 e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"d412346\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6eb43 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ec6eb43\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/intitucional_dark-scaled.jpg);\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Vamos construir novos projetos juntos?<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511938004723\">\n\t\t\t\t\t\tFale Conosco\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf3b8cd e-flex e-con-boxed lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"cf3b8cd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22cbd47 elementor-widget elementor-widget-heading\" data-id=\"22cbd47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Portf\u00f3lio de Obras<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ebbb50 elementor-widget elementor-widget-text-editor\" data-id=\"6ebbb50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Confira mais de nossos trabalhos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f64e2c elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2f64e2c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68f0fe8 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"68f0fe8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b5198 active-object-fit active-object-fit-true elementor-widget lastudio-kit elementor-lakit-gposts elementor-lakit-posts\" data-id=\"a8b5198\" data-element_type=\"widget\" data-widget_type=\"lakit-posts.default\">\n\t\t\t\t\t\n<div id=\"lapost_a8b5198\" class=\"lakit-posts layout-type-grid preset-grid-2 querycpt--post lakit-posts--grid\" data-item_selector=\".lakit-posts__item\" >        <div class=\"lakit-posts__list_wrapper\">\n            <div class=\"lakit-posts__list col-row\">\n            <div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-582 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/euroville\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Euroville&quot;\"><img decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-euroville.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-euroville.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-euroville-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/euroville\/\" title=\"Euroville\" rel=\"bookmark\">Euroville<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-695 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/stand-de-vendas\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Stand de Vendas&quot;\"><img decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Stand-de-Vendas.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Stand-de-Vendas.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Stand-de-Vendas-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/stand-de-vendas\/\" title=\"Stand de Vendas\" rel=\"bookmark\">Stand de Vendas<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-688 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/predios\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Pr\u00e9dios e Edif\u00edcios&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Predios-e-Edificios.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Predios-e-Edificios.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Predios-e-Edificios-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/predios\/\" title=\"Pr\u00e9dios e Edif\u00edcios\" rel=\"bookmark\">Pr\u00e9dios e Edif\u00edcios<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-721 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/teatro-em-sp\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Teatro em SP&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Teatro-em-SP.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Teatro-em-SP.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Teatro-em-SP-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/teatro-em-sp\/\" title=\"Teatro em SP\" rel=\"bookmark\">Teatro em SP<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-633 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villa-real\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Villa Real&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Villa-Real.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Villa-Real.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Villa-Real-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villa-real\/\" title=\"Villa Real\" rel=\"bookmark\">Villa Real<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-209 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/colinas-de-sao-francisco\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Colinas de S\u00e3o Francisco&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/03\/MINI-Colinas-de-sao-francisco-1.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/03\/MINI-Colinas-de-sao-francisco-1.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/03\/MINI-Colinas-de-sao-francisco-1-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/colinas-de-sao-francisco\/\" title=\"Colinas de S\u00e3o Francisco\" rel=\"bookmark\">Colinas de S\u00e3o Francisco<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-604 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/garden\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Garden&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-gardem.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-gardem.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-gardem-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/garden\/\" title=\"Garden\" rel=\"bookmark\">Garden<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-625 col-desk-4 col-tab-4\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/jardim-das-palmeiras\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Jardim das Palmeiras&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Jardim-das-Palmeiras.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Jardim-das-Palmeiras.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Jardim-das-Palmeiras-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/jardim-das-palmeiras\/\" title=\"Jardim das Palmeiras\" rel=\"bookmark\">Jardim das Palmeiras<\/a><\/h4><\/div><\/div><\/div>\n    <\/div>\n<\/div>            <\/div>\n        <\/div>\n    \n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c68d642 e-con-full e-flex lakit-col-width-auto-no e-container e-root-container elementor-top-section e-con e-parent\" data-id=\"c68d642\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12cd655 lakit-keep-mbl-yes elementor-hidden-desktop lakit-dots--vertical-no elementor-widget lastudio-kit elementor-lakit-gposts elementor-lakit-posts\" data-id=\"12cd655\" data-element_type=\"widget\" data-widget_type=\"lakit-posts.default\">\n\t\t\t\t\t\n<div id=\"lapost_12cd655\" class=\"lakit-posts layout-type-grid preset-grid-2 querycpt--post lakit-posts--grid lakit-carousel\" data-item_selector=\".lakit-posts__item\" data-slider_options=\"{&quot;slidesToScroll&quot;:{&quot;desktop&quot;:&quot;4&quot;,&quot;tablet&quot;:&quot;4&quot;},&quot;rows&quot;:{&quot;desktop&quot;:&quot;4&quot;,&quot;tablet&quot;:&quot;4&quot;},&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:false,&quot;infinite&quot;:true,&quot;centerMode&quot;:false,&quot;pauseOnHover&quot;:false,&quot;pauseOnInteraction&quot;:false,&quot;reverseDirection&quot;:false,&quot;infiniteEffect&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;variableWidth&quot;:false,&quot;prevArrow&quot;:&quot;.lakit-carousel__prev-arrow-12cd655&quot;,&quot;nextArrow&quot;:&quot;.lakit-carousel__next-arrow-12cd655&quot;,&quot;dotsElm&quot;:&quot;.lakit-carousel__dots_12cd655&quot;,&quot;rtl&quot;:false,&quot;effect&quot;:&quot;slide&quot;,&quot;coverflowEffect&quot;:{&quot;rotate&quot;:null,&quot;stretch&quot;:null,&quot;depth&quot;:null,&quot;modifier&quot;:null,&quot;scale&quot;:null},&quot;creativeEffect&quot;:{&quot;translateX&quot;:100},&quot;dotType&quot;:&quot;bullets&quot;,&quot;direction&quot;:&quot;horizontal&quot;,&quot;uniqueID&quot;:&quot;lakit_carousel_12cd655&quot;,&quot;asFor&quot;:&quot;&quot;,&quot;thumbs&quot;:&quot;&quot;,&quot;autoHeight&quot;:true,&quot;scrollbar&quot;:{&quot;enabled&quot;:true,&quot;el&quot;:&quot;.lakit-carousel__scrollbar_12cd655&quot;},&quot;directionbkp&quot;:{&quot;desktop&quot;:&quot;horizontal&quot;,&quot;mobile&quot;:&quot;horizontal&quot;,&quot;tablet&quot;:&quot;horizontal&quot;},&quot;slidesToShow&quot;:{&quot;desktop&quot;:&quot;1&quot;,&quot;tablet&quot;:&quot;1&quot;}}\" dir=\"ltr\" ><div class=\"lakit-carousel-inner\">        <div class=\"lakit-posts__list_wrapper swiper-container\" id=\"lakit_carousel_12cd655\">\n            <div class=\"lakit-posts__list swiper-wrapper\">\n            <div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-582 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/euroville\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Euroville&quot;\"><img decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-euroville.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-euroville.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-euroville-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/euroville\/\" title=\"Euroville\" rel=\"bookmark\">Euroville<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/euroville\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Euroville&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-688 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/predios\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Pr\u00e9dios e Edif\u00edcios&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Predios-e-Edificios.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Predios-e-Edificios.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Predios-e-Edificios-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/predios\/\" title=\"Pr\u00e9dios e Edif\u00edcios\" rel=\"bookmark\">Pr\u00e9dios e Edif\u00edcios<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/predios\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Pr\u00e9dios e Edif\u00edcios&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-625 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/jardim-das-palmeiras\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Jardim das Palmeiras&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Jardim-das-Palmeiras.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Jardim-das-Palmeiras.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Jardim-das-Palmeiras-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/jardim-das-palmeiras\/\" title=\"Jardim das Palmeiras\" rel=\"bookmark\">Jardim das Palmeiras<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/jardim-das-palmeiras\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Jardim das Palmeiras&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-650 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villagio-paradiso\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Villagio Paradiso&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Min-iVillagio-Paradiso.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Min-iVillagio-Paradiso.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Min-iVillagio-Paradiso-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villagio-paradiso\/\" title=\"Villagio Paradiso\" rel=\"bookmark\">Villagio Paradiso<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villagio-paradiso\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Villagio Paradiso&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-721 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/teatro-em-sp\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Teatro em SP&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Teatro-em-SP.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Teatro-em-SP.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Teatro-em-SP-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/teatro-em-sp\/\" title=\"Teatro em SP\" rel=\"bookmark\">Teatro em SP<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/teatro-em-sp\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Teatro em SP&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-604 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/garden\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Garden&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-gardem.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-gardem.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-gardem-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/garden\/\" title=\"Garden\" rel=\"bookmark\">Garden<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/garden\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Garden&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-695 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/stand-de-vendas\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Stand de Vendas&quot;\"><img decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Stand-de-Vendas.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Stand-de-Vendas.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Stand-de-Vendas-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/stand-de-vendas\/\" title=\"Stand de Vendas\" rel=\"bookmark\">Stand de Vendas<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/stand-de-vendas\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Stand de Vendas&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div><div class=\"lakit-posts__item has-post-thumbnail cpt-post post-item-633 swiper-slide\">\n    <div class=\"lakit-posts__outer-box\">\n        <div class=\"lakit-posts__inner-box\">            <div class=\"post-thumbnail lakit-posts__thumbnail\">\n                                    <a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villa-real\/\" class=\"lakit-posts__thumbnail-link\" aria-label=\"Read more about &quot;Villa Real&quot;\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"652\" src=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Villa-Real.jpg\" class=\"lakit-posts__thumbnail-img wp-post-image la-lazyload-image wp-post-image\" alt=\"\" srcset=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Villa-Real.jpg 640w, https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-content\/uploads\/2025\/04\/Mini-Villa-Real-294x300.jpg 294w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>\n                                                    \n                            <\/div>\n        <div class=\"lakit-posts__inner-content\"><div class=\"lakit-posts__inner-content-inner\"><h4 class=\"lakit-posts__title\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villa-real\/\" title=\"Villa Real\" rel=\"bookmark\">Villa Real<\/a><\/h4><div class=\"lakit-posts__more-wrap lakit-btn-more-wrap\"><a href=\"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/villa-real\/\" class=\"elementor-button lakit-posts__btn-more lakit-btn-more\" title=\"Ver Projeto &quot;Villa Real&quot;\" rel=\"bookmark\"><span class=\"btn__text\">Ver Projeto<\/span><\/a><\/div><\/div><\/div><\/div>\n    <\/div>\n<\/div>            <\/div>\n        <\/div>\n    <\/div><div class=\"lakit-carousel__scrollbar swiper-scrollbar lakit-carousel__scrollbar_12cd655\"><\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sobre N\u00f3s Institucional 2J Engenharia Do planejamento \u00e0 entrega da obra, oferecemos um acompanhamento completo, com infraestrutura moderna e uma equipe qualificada para enfrentar os desafios mais inovadores da engenharia civil. Utilizamos tecnologia avan\u00e7ada e processos eficientes para garantir os melhores resultados. Adotamos o conceito one-stop-shop, reunindo todas as solu\u00e7\u00f5es de engenharia em um s\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-837","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/pages\/837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/comments?post=837"}],"version-history":[{"count":0,"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/pages\/837\/revisions"}],"wp:attachment":[{"href":"https:\/\/hospedagens.mtzhost.com.br\/sites\/2jengenharia\/wp-json\/wp\/v2\/media?parent=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}